{"id":4984,"date":"2025-06-05T15:14:40","date_gmt":"2025-06-05T15:14:40","guid":{"rendered":"https:\/\/ementa.ogaveto.com\/staging\/?page_id=4984"},"modified":"2025-11-17T16:44:03","modified_gmt":"2025-11-17T16:44:03","slug":"krug-clos-du-mesnil","status":"publish","type":"page","link":"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-clos-du-mesnil\/","title":{"rendered":"KRUG Clos du Mesnil"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin_tablet=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produto&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748514688073{margin-bottom: 0px !important;background-color: #f1efec !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;titulo&#8221;]\n<h1 style=\"text-align: left;\"><span style=\"color: #5e0027;\"><span style=\"color: #000000;\">KRUG CLOS DU MESNIL<\/span><\/span><\/h1>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;edicao&#8221; css=&#8221;.vc_custom_1748450108094{margin-top: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 1px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 5px !important;padding-bottom: 20px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #c1c1c1 !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;2&#8243; column_layout_using_2_columns=&#8221;large_first&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;right&#8221; col_1_text_element=&#8221;p&#8221; col_2_text_element=&#8221;p&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;none&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;2009&#8243; col_2_content=&#8221;1750\u20ac&#8221;][vc_column_text css=&#8221;.vc_custom_1748514937000{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 2px !important;padding-right: 5px !important;padding-bottom: 2px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #e0e0e0 !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #5e0027;\"><strong>Chardonnay<\/strong><\/span><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;edicao&#8221; css=&#8221;.vc_custom_1748450108094{margin-top: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 1px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 5px !important;padding-bottom: 20px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #c1c1c1 !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;2&#8243; column_layout_using_2_columns=&#8221;large_first&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;right&#8221; col_1_text_element=&#8221;p&#8221; col_2_text_element=&#8221;p&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;none&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;2008&#8243; col_2_content=&#8221;1950\u20ac&#8221;][vc_column_text css=&#8221;.vc_custom_1748514937000{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 2px !important;padding-right: 5px !important;padding-bottom: 2px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #e0e0e0 !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #5e0027;\"><strong>Chardonnay<\/strong><\/span><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;edicao&#8221; css=&#8221;.vc_custom_1748450579841{border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 1px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 5px !important;padding-bottom: 20px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #c1c1c1 !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;2&#8243; column_layout_using_2_columns=&#8221;large_first&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;right&#8221; col_1_text_element=&#8221;p&#8221; col_2_text_element=&#8221;p&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;none&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;2004&#8243; col_2_content=&#8221;1650\u20ac&#8221;][vc_column_text css=&#8221;.vc_custom_1748514872539{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 2px !important;padding-right: 5px !important;padding-bottom: 2px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #e0e0e0 !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #5e0027;\"><strong>Chardonnay<\/strong><\/span><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;.vc_custom_1749468711111{background-color: #f1efec !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;titulo&#8221;]\n<h5 style=\"text-align: center;\">The Purity of Origin, the Essence of Chardonnay.<\/h5>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Among Maison Krug&#8217;s rarest creations, <strong>Krug Clos du Mesnil<\/strong> is a tribute to extreme purity: a single terroir, a single grape variety, a single year. From a walled vineyard of just 1.84 hectares, located in the heart of Le Mesnil-sur-Oger &#8211; one of the most revered crus on the C\u00f4te des Blancs &#8211; this exceptional champagne translates the purified expression of Chardonnay like no other.<\/p>\n<p>Surrounded by walls since the 17th century, Clos du Mesnil remains a place apart, where each harvest is rigorously assessed and only the truly extraordinary years are chosen to give rise to this champagne. Its mineral elegance, firm structure and delicate tension reveal the most sculpted and luminous side of the grape variety, in a champagne of great precision and character.<\/p>\n<p>More than a vintage, <strong>Krug Clos du Mesnil<\/strong> is a rare piece of oenological haute couture, created to emphasise moments of contemplation and celebration with discretion and refinement.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;middle&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;coluna-krug&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;4779&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; translate_y_desktop=&#8221;40px&#8221; translate_y_tablet=&#8221;0&#8243; translate_y_phone=&#8221;0&#8243; margin_top=&#8221;30px&#8221; el_class=&#8221;product-image&#8221; max_width_custom=&#8221;65%&#8221; max_width_custom_tablet=&#8221;120px&#8221; max_width_custom_phone=&#8221;80px&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;second-text&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1749469063123{background-color: #f1efec !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;titulo&#8221;]\n<h5 style=\"text-align: center;\">How to Enjoy Krug Clos Du Mesnil: Food Pairings and Recommendations.<\/h5>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: justify;\">Krug Clos du Mesnil is a champagne of verticality and precision, designed to enhance the purest flavours of gastronomy. Its vibrant freshness, deep minerality and aromatic complexity call for dishes that respect this nobility and let the terroir do the talking. At <strong>O Gaveto<\/strong> Restaurant, the following pairings stand out:<\/p>\n<ul>\n<li>\n<p style=\"text-align: justify;\"><strong data-start=\"1679\" data-end=\"1699\">Fresh seafood<\/strong> \u2013 The delicacy of natural clams, lobster or crab is echoed in the vibrant minerality and purity of Clos du Mesnil, creating a direct link between sea and soil.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\"><strong data-start=\"1877\" data-end=\"1916\">Grilled or cooked fish<\/strong> \u2013 Sea bass, sole or turbot reveal all their elegance when accompanied by this precise Chardonnay, which respects the flavour of the fish and adds depth to the dish.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\"><strong data-start=\"2098\" data-end=\"2126\">Delicate sea rice<\/strong> \u2013 Dishes such as lobster rice, where the flavour of the sea merges with the texture of the rice, take on a new dimension with the tension and persistence of Krug Clos du Mesnil.<\/p>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">To best appreciate the elegance and precision of Krug Clos du Mesnil, we recommend tasting it between 10\u00baC and 12\u00baC, in wide-rimmed white wine glasses that allow its mineral, floral and citrus aromas to breathe and fully express themselves.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;75px&#8221; bottom_padding=&#8221;0px&#8221; top_padding_tablet=&#8221;20px&#8221; top_padding_phone=&#8221;10px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produtos&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;0&#8243; border_top_desktop=&#8221;1&#8243; border_right_desktop=&#8221;1&#8243; border_bottom_desktop=&#8221;1&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;1&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;1&#8243; column_border_color=&#8221;#5e0027&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748360062609{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG ROS\u00c9[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1749468789007{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]The Elegance of Colour, the Art of Complexity.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1749468825210{margin-top: 35px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-rose\/\"><span style=\"text-decoration: underline;\">See More<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;0&#8243; border_top_desktop=&#8221;1&#8243; border_right_desktop=&#8221;0&#8243; border_bottom_desktop=&#8221;1&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;0&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;0&#8243; column_border_color=&#8221;#5e0027&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748534203849{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG GRANDE CUV\u00c9E[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1749468843005{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]The Generosity of Champagne, Elevated to Art.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1749639344012{margin-top: 35px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-grande-cuvee\/\"><span style=\"text-decoration: underline;\">See More<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1&#8243; border_top_desktop=&#8221;1&#8243; border_right_desktop=&#8221;0&#8243; border_bottom_desktop=&#8221;1&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;1&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;0&#8243; column_border_color=&#8221;#5e0027&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748360082000{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG CLOS D&#8217;AMBONNAY[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1749468908962{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]The Intensity of Origin, the Essence of Pinot Noir.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1749468950068{margin-top: 35px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-clos-dambonnay\/\"><span style=\"text-decoration: underline;\">See More<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0px&#8221; bottom_padding=&#8221;0px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produtos-2&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;0&#8243; border_top_desktop=&#8221;0&#8243; border_right_desktop=&#8221;1&#8243; border_bottom_desktop=&#8221;0&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;1&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;1&#8243; column_border_color=&#8221;#5e0027&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748360092671{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG VINTAGE[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1749468968173{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]The Story of a Year, Captured in its Fullness.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1749468998949{padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-vintage\/\"><span style=\"text-decoration: underline;\">See More<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;0&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;1&#8243; border_left_phone=&#8221;1&#8243; border_top_phone=&#8221;0&#8243; border_right_phone=&#8221;1&#8243; border_bottom_phone=&#8221;1&#8243; column_border_color=&#8221;#000000&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1763397746974{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG COLLECTION[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1763397774263{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]Time\u2019s second revelation of Krug Vintage.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1763397791372{padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-collection\/\"><span style=\"text-decoration: underline;\">See More<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1&#8243; column_border_color=&#8221;#000000&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#0a0a0a&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;1px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;straight_section&#8221;][vc_column top_padding_desktop=&#8221;30px&#8221; bottom_padding_desktop=&#8221;30px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;0&#8243; border_top_desktop=&#8221;1&#8243; border_right_desktop=&#8221;0&#8243; border_bottom_desktop=&#8221;1&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;0&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;1&#8243; column_border_color=&#8221;#0a0a0a&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1749469024631{padding-top: 10px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h4><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/en\/\">\u2190 Back to Menu<\/a><\/span><\/h4>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin_tablet=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produto&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4984","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KRUG Clos du Mesnil - Gaveto<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KRUG Clos du Mesnil - Gaveto\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin_tablet=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produto&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-clos-du-mesnil\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaveto\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T16:44:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/en\\\/krug-clos-du-mesnil\\\/\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/en\\\/krug-clos-du-mesnil\\\/\",\"name\":\"KRUG Clos du Mesnil - Gaveto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/#website\"},\"datePublished\":\"2025-06-05T15:14:40+00:00\",\"dateModified\":\"2025-11-17T16:44:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/en\\\/krug-clos-du-mesnil\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/en\\\/krug-clos-du-mesnil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/en\\\/krug-clos-du-mesnil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KRUG Clos du Mesnil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/#website\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/\",\"name\":\"Gaveto\",\"description\":\"Ementa Digital\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KRUG Clos du Mesnil - Gaveto","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"KRUG Clos du Mesnil - Gaveto","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin_tablet=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produto&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...","og_url":"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-clos-du-mesnil\/","og_site_name":"Gaveto","article_modified_time":"2025-11-17T16:44:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-clos-du-mesnil\/","url":"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-clos-du-mesnil\/","name":"KRUG Clos du Mesnil - Gaveto","isPartOf":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/#website"},"datePublished":"2025-06-05T15:14:40+00:00","dateModified":"2025-11-17T16:44:03+00:00","breadcrumb":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-clos-du-mesnil\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ementa.ogaveto.com\/staging\/en\/krug-clos-du-mesnil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ementa.ogaveto.com\/staging\/en\/krug-clos-du-mesnil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ementa.ogaveto.com\/staging\/en\/"},{"@type":"ListItem","position":2,"name":"KRUG Clos du Mesnil"}]},{"@type":"WebSite","@id":"https:\/\/ementa.ogaveto.com\/staging\/#website","url":"https:\/\/ementa.ogaveto.com\/staging\/","name":"Gaveto","description":"Ementa Digital","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ementa.ogaveto.com\/staging\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/en\/wp-json\/wp\/v2\/pages\/4984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ementa.ogaveto.com\/staging\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ementa.ogaveto.com\/staging\/en\/wp-json\/wp\/v2\/comments?post=4984"}],"version-history":[{"count":0,"href":"https:\/\/ementa.ogaveto.com\/staging\/en\/wp-json\/wp\/v2\/pages\/4984\/revisions"}],"wp:attachment":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/en\/wp-json\/wp\/v2\/media?parent=4984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}