{"id":4922,"date":"2025-05-29T10:29:49","date_gmt":"2025-05-29T10:29:49","guid":{"rendered":"https:\/\/ementa.ogaveto.com\/staging\/?page_id=4922"},"modified":"2025-11-17T16:02:34","modified_gmt":"2025-11-17T16:02:34","slug":"krug-clos-du-mesnil","status":"publish","type":"page","link":"https:\/\/ementa.ogaveto.com\/staging\/krug-clos-du-mesnil\/","title":{"rendered":"KRUG Clos du Mesnil"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin_tablet=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produto&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748514688073{margin-bottom: 0px !important;background-color: #f1efec !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;titulo&#8221;]\n<h1 style=\"text-align: left;\"><span style=\"color: #5e0027;\"><span style=\"color: #000000;\">KRUG CLOS DU MESNIL<\/span><\/span><\/h1>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;edicao&#8221; css=&#8221;.vc_custom_1748450108094{margin-top: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 1px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 5px !important;padding-bottom: 20px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #c1c1c1 !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;2&#8243; column_layout_using_2_columns=&#8221;large_first&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;right&#8221; col_1_text_element=&#8221;p&#8221; col_2_text_element=&#8221;p&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;none&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;2009&#8243; col_2_content=&#8221;1750\u20ac&#8221;][vc_column_text css=&#8221;.vc_custom_1748514937000{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 2px !important;padding-right: 5px !important;padding-bottom: 2px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #e0e0e0 !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #5e0027;\"><strong>Chardonnay<\/strong><\/span><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;edicao&#8221; css=&#8221;.vc_custom_1748450108094{margin-top: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 1px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 5px !important;padding-bottom: 20px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #c1c1c1 !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;2&#8243; column_layout_using_2_columns=&#8221;large_first&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;right&#8221; col_1_text_element=&#8221;p&#8221; col_2_text_element=&#8221;p&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;none&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;2008&#8243; col_2_content=&#8221;1950\u20ac&#8221;][vc_column_text css=&#8221;.vc_custom_1748514937000{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 2px !important;padding-right: 5px !important;padding-bottom: 2px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #e0e0e0 !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #5e0027;\"><strong>Chardonnay<\/strong><\/span><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;edicao&#8221; css=&#8221;.vc_custom_1748450579841{border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 1px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 5px !important;padding-bottom: 20px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #c1c1c1 !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;2&#8243; column_layout_using_2_columns=&#8221;large_first&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;right&#8221; col_1_text_element=&#8221;p&#8221; col_2_text_element=&#8221;p&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;none&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;2004&#8243; col_2_content=&#8221;1650\u20ac&#8221;][vc_column_text css=&#8221;.vc_custom_1748514872539{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 2px !important;padding-right: 5px !important;padding-bottom: 2px !important;padding-left: 5px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: #e0e0e0 !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #5e0027;\"><strong>Chardonnay<\/strong><\/span><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;.vc_custom_1748534117686{background-color: #f1efec !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;titulo&#8221;]\n<h5 style=\"text-align: center;\">A Pureza da Origem, a Ess\u00eancia do Chardonnay.<\/h5>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p data-start=\"335\" data-end=\"715\">Entre as cria\u00e7\u00f5es mais raras da Maison Krug, o <strong>Krug Clos du Mesnil<\/strong> \u00e9 uma homenagem \u00e0 pureza extrema: um s\u00f3 terroir, uma s\u00f3 casta, um s\u00f3 ano. Proveniente de um vinhedo murado de apenas 1,84 hectares, situado no cora\u00e7\u00e3o de Le Mesnil-sur-Oger \u2014 um dos crus mais reverenciados da C\u00f4te des Blancs \u2014 este champagne de exce\u00e7\u00e3o traduz como nenhum outro a express\u00e3o depurada do Chardonnay.<\/p>\n<p data-start=\"717\" data-end=\"1098\">Cercado por muros desde o s\u00e9culo XVII, o Clos du Mesnil permanece como um lugar \u00e0 parte, onde cada colheita \u00e9 avaliada com rigor e apenas os anos verdadeiramente extraordin\u00e1rios s\u00e3o escolhidos para dar origem a este champagne. A sua eleg\u00e2ncia mineral, estrutura firme e delicada tens\u00e3o revelam o lado mais esculpido e luminoso da casta, num champagne de grande precis\u00e3o e car\u00e1cter.<\/p>\n<p data-start=\"1100\" data-end=\"1272\">Mais do que um vintage, <strong>Krug Clos du Mesnil<\/strong> \u00e9 uma pe\u00e7a rara da alta-costura enol\u00f3gica, criada para sublinhar momentos de contempla\u00e7\u00e3o e celebra\u00e7\u00e3o com discri\u00e7\u00e3o e requinte.<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;middle&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;coluna-krug&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;4779&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; translate_y_desktop=&#8221;40px&#8221; translate_y_tablet=&#8221;0&#8243; translate_y_phone=&#8221;0&#8243; margin_top=&#8221;30px&#8221; el_class=&#8221;product-image&#8221; max_width_custom=&#8221;65%&#8221; max_width_custom_tablet=&#8221;120px&#8221; max_width_custom_phone=&#8221;80px&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;second-text&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748515436801{background-color: #f1efec !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;titulo&#8221;]\n<h5 style=\"text-align: center;\">Como Apreciar o Krug Clos Du Mesnil: Harmoniza\u00e7\u00f5es e Recomenda\u00e7\u00f5es.<\/h5>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: justify;\">O Krug Clos du Mesnil \u00e9 um champagne de verticalidade e precis\u00e3o, pensado para real\u00e7ar os sabores mais puros da gastronomia. A sua frescura vibrante, mineralidade profunda e complexidade arom\u00e1tica pedem pratos que respeitem essa nobreza e deixem o terroir falar. No Restaurante <strong>O Gaveto<\/strong>, destacam-se as seguintes harmoniza\u00e7\u00f5es:<\/p>\n<ul>\n<li>\n<p style=\"text-align: justify;\"><strong data-start=\"1679\" data-end=\"1699\">Mariscos frescos<\/strong> \u2013 A delicadeza de am\u00eaijoas, lavagante ou sapateira ao natural encontra eco na mineralidade vibrante e na pureza do Clos du Mesnil, criando uma liga\u00e7\u00e3o direta entre mar e solo.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\"><strong data-start=\"1877\" data-end=\"1916\">Peixes grelhados ou cozidos<\/strong> \u2013 Robalo, linguado ou rodovalho revelam toda a sua eleg\u00e2ncia quando acompanhados por este Chardonnay de precis\u00e3o, que respeita o sabor do peixe e acrescenta profundidade ao prato.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\"><strong data-start=\"2098\" data-end=\"2126\">Arrozes delicados do mar<\/strong> \u2013 Pratos como o arroz de lavagante, onde o sabor do mar se funde com a textura do arroz, ganham nova dimens\u00e3o com a tens\u00e3o e persist\u00eancia do Krug Clos du Mesnil.<\/p>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Para melhor apreciar a eleg\u00e2ncia e a precis\u00e3o do Krug Clos du Mesnil, recomendamos degustar entre 10\u00baC e 12\u00baC, em copos de vinho branco de grande abertura, que permitam a respira\u00e7\u00e3o e plena express\u00e3o dos seus aromas minerais, florais e c\u00edtricos.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;75px&#8221; bottom_padding=&#8221;0px&#8221; top_padding_tablet=&#8221;20px&#8221; top_padding_phone=&#8221;10px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produtos&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;0&#8243; border_top_desktop=&#8221;1&#8243; border_right_desktop=&#8221;1&#8243; border_bottom_desktop=&#8221;1&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;1&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;1&#8243; column_border_color=&#8221;#5e0027&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748360062609{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG ROS\u00c9[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748534132787{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]A Eleg\u00e2ncia da Cor, a Arte da Complexidade.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748534168564{margin-top: 35px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/krug-rose\/\"><span style=\"text-decoration: underline;\">Ver Mais<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;0&#8243; border_top_desktop=&#8221;1&#8243; border_right_desktop=&#8221;0&#8243; border_bottom_desktop=&#8221;1&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;0&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;0&#8243; column_border_color=&#8221;#5e0027&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748534203849{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG GRANDE CUV\u00c9E[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748534239336{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]A Generosidade do Champagne, Elevada \u00e0 Arte.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748534265093{margin-top: 35px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/krug-grande-cuvee\/\"><span style=\"text-decoration: underline;\">Ver Mais<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1&#8243; border_top_desktop=&#8221;1&#8243; border_right_desktop=&#8221;0&#8243; border_bottom_desktop=&#8221;1&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;1&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;0&#8243; column_border_color=&#8221;#5e0027&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748360082000{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG CLOS D&#8217;AMBONNAY[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748534295815{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]A Intensidade da Origem, a Ess\u00eancia do Pinot Noir.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748534320078{margin-top: 35px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/krug-clos-dambonnay\/\"><span style=\"text-decoration: underline;\">Ver Mais<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0px&#8221; bottom_padding=&#8221;0px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produtos-2&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;0&#8243; border_top_desktop=&#8221;0&#8243; border_right_desktop=&#8221;1&#8243; border_bottom_desktop=&#8221;0&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;1&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;1&#8243; column_border_color=&#8221;#5e0027&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748360092671{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG VINTAGE[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748534345774{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]A Hist\u00f3ria de um Ano, Captada na sua Plenitude.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748534371972{padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/krug-vintage\/\"><span style=\"text-decoration: underline;\">Ver Mais<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;0&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;1&#8243; border_left_phone=&#8221;1&#8243; border_top_phone=&#8221;0&#8243; border_right_phone=&#8221;1&#8243; border_bottom_phone=&#8221;1&#8243; column_border_color=&#8221;#000000&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1763395131025{margin-bottom: 10px !important;padding-top: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title&#8221;]KRUG COLLECTION[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1763395150623{margin-bottom: 15px !important;padding-right: 20px !important;padding-bottom: 0px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]A segunda revela\u00e7\u00e3o do Krug Vintage com o tempo como Mestre.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1763395171265{padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\/krug-collection\/\"><span style=\"text-decoration: underline;\">Ver Mais<\/span> \u2192<\/a><\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1&#8243; column_border_color=&#8221;#000000&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#0a0a0a&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;1px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;straight_section&#8221;][vc_column top_padding_desktop=&#8221;30px&#8221; bottom_padding_desktop=&#8221;30px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;0&#8243; border_top_desktop=&#8221;1&#8243; border_right_desktop=&#8221;0&#8243; border_bottom_desktop=&#8221;1&#8243; border_left_tablet=&#8221;1&#8243; border_top_tablet=&#8221;0&#8243; border_right_tablet=&#8221;1&#8243; border_bottom_tablet=&#8221;1&#8243; column_border_color=&#8221;#0a0a0a&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748337079935{padding-top: 10px !important;padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h4><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/ementa.ogaveto.com\/staging\">\u2190 Voltar ao Menu<\/a><\/span><\/h4>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin_tablet=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produto&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4922","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KRUG Clos du Mesnil - Gaveto<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KRUG Clos du Mesnil - Gaveto\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin_tablet=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produto&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ementa.ogaveto.com\/staging\/krug-clos-du-mesnil\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaveto\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T16:02:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/krug-clos-du-mesnil\\\/\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/krug-clos-du-mesnil\\\/\",\"name\":\"KRUG Clos du Mesnil - Gaveto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/#website\"},\"datePublished\":\"2025-05-29T10:29:49+00:00\",\"dateModified\":\"2025-11-17T16:02:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/krug-clos-du-mesnil\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/krug-clos-du-mesnil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/krug-clos-du-mesnil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KRUG Clos du Mesnil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/#website\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/\",\"name\":\"Gaveto\",\"description\":\"Ementa Digital\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KRUG Clos du Mesnil - Gaveto","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"KRUG Clos du Mesnil - Gaveto","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin_tablet=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;produto&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...","og_url":"https:\/\/ementa.ogaveto.com\/staging\/krug-clos-du-mesnil\/","og_site_name":"Gaveto","article_modified_time":"2025-11-17T16:02:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ementa.ogaveto.com\/staging\/krug-clos-du-mesnil\/","url":"https:\/\/ementa.ogaveto.com\/staging\/krug-clos-du-mesnil\/","name":"KRUG Clos du Mesnil - Gaveto","isPartOf":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/#website"},"datePublished":"2025-05-29T10:29:49+00:00","dateModified":"2025-11-17T16:02:34+00:00","breadcrumb":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/krug-clos-du-mesnil\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ementa.ogaveto.com\/staging\/krug-clos-du-mesnil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ementa.ogaveto.com\/staging\/krug-clos-du-mesnil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ementa.ogaveto.com\/staging\/"},{"@type":"ListItem","position":2,"name":"KRUG Clos du Mesnil"}]},{"@type":"WebSite","@id":"https:\/\/ementa.ogaveto.com\/staging\/#website","url":"https:\/\/ementa.ogaveto.com\/staging\/","name":"Gaveto","description":"Ementa Digital","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ementa.ogaveto.com\/staging\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/pages\/4922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/comments?post=4922"}],"version-history":[{"count":0,"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/pages\/4922\/revisions"}],"wp:attachment":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/media?parent=4922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}