{"id":262,"date":"2020-05-16T21:10:21","date_gmt":"2020-05-16T21:10:21","guid":{"rendered":"https:\/\/ementa.ogaveto.com\/staging\/?post_type=item&#038;p=262"},"modified":"2025-05-01T18:29:13","modified_gmt":"2025-05-01T18:29:13","slug":"nossa-calcario-bairrada-bical-2017","status":"publish","type":"vinho","link":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/","title":{"rendered":"NOSSA Calc\u00e1rio"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":263,"parent":0,"template":"","categoria_vinhos":[131,128],"class_list":["post-262","vinho","type-vinho","status-publish","has-post-thumbnail","categoria_vinhos-bairrada-en","categoria_vinhos-white-wine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NOSSA Calc\u00e1rio - Gaveto<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOSSA Calc\u00e1rio - Gaveto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaveto\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-01T18:29:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/05\/Nossa-Branco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/nossa-calcario-bairrada-bical-2017\\\/\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/nossa-calcario-bairrada-bical-2017\\\/\",\"name\":\"NOSSA Calc\u00e1rio - Gaveto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/nossa-calcario-bairrada-bical-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/nossa-calcario-bairrada-bical-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Nossa-Branco.jpg\",\"datePublished\":\"2020-05-16T21:10:21+00:00\",\"dateModified\":\"2025-05-01T18:29:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/nossa-calcario-bairrada-bical-2017\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/nossa-calcario-bairrada-bical-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/nossa-calcario-bairrada-bical-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Nossa-Branco.jpg\",\"contentUrl\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Nossa-Branco.jpg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/nossa-calcario-bairrada-bical-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vinhos\",\"item\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NOSSA Calc\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/#website\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/\",\"name\":\"Gaveto\",\"description\":\"Ementa Digital\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NOSSA Calc\u00e1rio - Gaveto","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"NOSSA Calc\u00e1rio - Gaveto","og_url":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/","og_site_name":"Gaveto","article_modified_time":"2025-05-01T18:29:13+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/05\/Nossa-Branco.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/","url":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/","name":"NOSSA Calc\u00e1rio - Gaveto","isPartOf":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/#primaryimage"},"image":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/05\/Nossa-Branco.jpg","datePublished":"2020-05-16T21:10:21+00:00","dateModified":"2025-05-01T18:29:13+00:00","breadcrumb":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/#primaryimage","url":"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/05\/Nossa-Branco.jpg","contentUrl":"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/05\/Nossa-Branco.jpg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/nossa-calcario-bairrada-bical-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ementa.ogaveto.com\/staging\/"},{"@type":"ListItem","position":2,"name":"Vinhos","item":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/"},{"@type":"ListItem","position":3,"name":"NOSSA Calc\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/ementa.ogaveto.com\/staging\/#website","url":"https:\/\/ementa.ogaveto.com\/staging\/","name":"Gaveto","description":"Ementa Digital","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ementa.ogaveto.com\/staging\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/vinho\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/vinho"}],"about":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/types\/vinho"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/media\/263"}],"wp:attachment":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/media?parent=262"}],"wp:term":[{"taxonomy":"categoria_vinhos","embeddable":true,"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/categoria_vinhos?post=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}