{"id":713,"date":"2020-06-11T20:49:34","date_gmt":"2020-06-11T20:49:34","guid":{"rendered":"https:\/\/ementa.ogaveto.com\/staging\/?post_type=vinho&#038;p=713"},"modified":"2024-02-18T22:57:38","modified_gmt":"2024-02-18T22:57:38","slug":"qta-vale-dona-maria-vinha-francisca","status":"publish","type":"vinho","link":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/","title":{"rendered":"Qta. Vale Dona Maria Vinha Francisca"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1005,"parent":0,"template":"","categoria_vinhos":[139,136],"class_list":["post-713","vinho","type-vinho","status-publish","has-post-thumbnail","categoria_vinhos-douro-en-2","categoria_vinhos-red-wine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qta. Vale Dona Maria Vinha Francisca - Gaveto<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qta. Vale Dona Maria Vinha Francisca - Gaveto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaveto\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-18T22:57:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/06\/vdm-vf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"149\" \/>\n\t<meta property=\"og:image:height\" content=\"215\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/qta-vale-dona-maria-vinha-francisca\\\/\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/qta-vale-dona-maria-vinha-francisca\\\/\",\"name\":\"Qta. Vale Dona Maria Vinha Francisca - Gaveto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/qta-vale-dona-maria-vinha-francisca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/qta-vale-dona-maria-vinha-francisca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/vdm-vf.jpg\",\"datePublished\":\"2020-06-11T20:49:34+00:00\",\"dateModified\":\"2024-02-18T22:57:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/qta-vale-dona-maria-vinha-francisca\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/qta-vale-dona-maria-vinha-francisca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/qta-vale-dona-maria-vinha-francisca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/vdm-vf.jpg\",\"contentUrl\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/vdm-vf.jpg\",\"width\":149,\"height\":215},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/qta-vale-dona-maria-vinha-francisca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vinhos\",\"item\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/vinho\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qta. Vale Dona Maria Vinha Francisca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/#website\",\"url\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/\",\"name\":\"Gaveto\",\"description\":\"Ementa Digital\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ementa.ogaveto.com\\\/staging\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qta. Vale Dona Maria Vinha Francisca - Gaveto","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"Qta. Vale Dona Maria Vinha Francisca - Gaveto","og_url":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/","og_site_name":"Gaveto","article_modified_time":"2024-02-18T22:57:38+00:00","og_image":[{"width":149,"height":215,"url":"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/06\/vdm-vf.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/","url":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/","name":"Qta. Vale Dona Maria Vinha Francisca - Gaveto","isPartOf":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/#primaryimage"},"image":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/#primaryimage"},"thumbnailUrl":"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/06\/vdm-vf.jpg","datePublished":"2020-06-11T20:49:34+00:00","dateModified":"2024-02-18T22:57:38+00:00","breadcrumb":{"@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/#primaryimage","url":"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/06\/vdm-vf.jpg","contentUrl":"https:\/\/ementa.ogaveto.com\/staging\/wp-content\/uploads\/2020\/06\/vdm-vf.jpg","width":149,"height":215},{"@type":"BreadcrumbList","@id":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/qta-vale-dona-maria-vinha-francisca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ementa.ogaveto.com\/staging\/"},{"@type":"ListItem","position":2,"name":"Vinhos","item":"https:\/\/ementa.ogaveto.com\/staging\/vinho\/"},{"@type":"ListItem","position":3,"name":"Qta. Vale Dona Maria Vinha Francisca"}]},{"@type":"WebSite","@id":"https:\/\/ementa.ogaveto.com\/staging\/#website","url":"https:\/\/ementa.ogaveto.com\/staging\/","name":"Gaveto","description":"Ementa Digital","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ementa.ogaveto.com\/staging\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/vinho\/713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/vinho"}],"about":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/types\/vinho"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/media\/1005"}],"wp:attachment":[{"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/media?parent=713"}],"wp:term":[{"taxonomy":"categoria_vinhos","embeddable":true,"href":"https:\/\/ementa.ogaveto.com\/staging\/wp-json\/wp\/v2\/categoria_vinhos?post=713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}